{"id":1837,"date":"2024-07-10T11:42:28","date_gmt":"2024-07-10T18:42:28","guid":{"rendered":"https:\/\/help.lichenportal.org\/?page_id=1837"},"modified":"2026-05-12T10:36:12","modified_gmt":"2026-05-12T17:36:12","slug":"analisis-de-metabolitos-secundarios","status":"publish","type":"page","link":"https:\/\/help.lichenportal.org\/index.php\/es\/analisis-de-metabolitos-secundarios\/","title":{"rendered":"Software para la An\u00e1lisis de Metabolitos Secundarios"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-large-font-size\">MYTABOLITES<\/h2>\n\n\n\n<p>\u2013 <strong>un programa de Daryl Lafferty, Arizona State University<\/strong> \u2013 <br>(Idea original: E. Mietzsch, H.T. Lumbsch &amp; J.A. Elix)<\/p>\n\n\n\n<p>[traducci\u00f3n de la pagina: <strong>Mar\u00eda de los \u00c1ngeles (Marusa) Herrera-Campos<\/strong> y <strong>Rosa Emilia P\u00e9rez-P\u00e9rez<\/strong>]<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><font color=\"red\">IMPORTANTE !!!<\/font><\/p>\n\n\n\n<p class=\"has-small-font-size\"><font color=\"red\"><strong>Actualice a la versi\u00f3n m\u00e1s reciente (1.2.2.0)<\/strong>. Cuando intenta actualizar la base de datos con una versi\u00f3n anterior, parece funcionando pero terminar\u00e1 con un conjunto de datos incompleto que no permite revisar la base de datos de los l\u00edquenes.<\/font><\/p>\n\n\n\n<p><em><strong>Mytabolites<\/strong><\/em>es un programa escrito por Daryl Lafferty en colaboraci\u00f3n con Frank Bungartz (Arizona State University), John A. Elix (Australian National University) y <a href=\"http:\/\/www.fschumm.de\/\">Felix<\/a> <a href=\"http:\/\/www.fschumm.de\/\">Schumm<\/a> (Wangen) para ayudar en la interpretaci\u00f3n de placas de cromatograf\u00eda de capa fina para el an\u00e1lisis de metabolitos secundarios de l\u00edquenes.<\/p>\n\n\n\n<p>Este programa comparte muchas funcionalidades con su antecesor, un software originalmente desarrollado en la Universidad de Essen (Alemania) por Esther Mietzsch- Lumbsch y H. Thorsten Lumbsch, en colaboraci\u00f3n con John A. Elix (Australian National University). Los autores nos permitieron generosamente adaptar su idea original para escribir una versi\u00f3n m\u00e1s funcional, la cual est\u00e1 disponible en este portal.<\/p>\n\n\n\n<p>Los datos de la cromatograf\u00eda incluidos en Mytabolites vienen de la edici\u00f3n m\u00e1s reciente del <a href=\"https:\/\/www.anbg.gov.au\/abrs\/lichenlist\/TLC%20Cat%206MC.pdf\"><em>Catalogue of Standardized Chromatographic Data and Biosynthetic<\/em> <em>Relationships for Lichen Substances<\/em><\/a><em> <\/em>(actualizado regularmente por el autor y en el Consorcio de Herbarios de L\u00edquenes), publicado y distribuido por el autor, J. A. Elix. Los cromatogramas utilizados por el programa fueron publicado originalmente por F. Schumm &amp; J. A. Elix en el <em>Atlas of Images of Thin Layer Chromatograms of Lichen Substances <\/em>(<a href=\"https:\/\/www.bod.com\/\">Books on Demand<\/a>, 2015) y en el suplemento (<a href=\"https:\/\/buchshop.bod.de\/atlas-of-images-of-thin-layer-chromatograms-of-lichen-substances-supplement-felix-schumm-9783743145863\">Books on Demand<\/a>, 2016).<\/p>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"625\" height=\"625\" src=\"http:\/\/help.lichenportal.org\/wp-content\/uploads\/2019\/06\/Wintabolites_Icon_solarized.jpg\" alt=\"\" class=\"wp-image-109\" style=\"width:221px;height:auto\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2019\/06\/Wintabolites_Icon_solarized.jpg 625w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2019\/06\/Wintabolites_Icon_solarized-150x150.jpg 150w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2019\/06\/Wintabolites_Icon_solarized-300x300.jpg 300w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/figure><\/div>\n\n\n<p>La versi\u00f3n original de Wintabolites fue escrita en Windows de 16 bit. As\u00ed que no es compatible con computadoras de 64 bit. Mytabolites solamente corre en Windows (no est\u00e1 disponible para Mac); y actualmente solo existe la versi\u00f3n de Mytabolites en el idioma Ingl\u00e9s. Una alternativa para la identificaci\u00f3n de metabolitos secundarios es utilizar <a href=\"http:\/\/www.navikey.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">NaviKey<\/a> que no depende del sistema operativo y est\u00e1 disponible como <em><a href=\"http:\/\/liaslight.lias.net\/Identification\/Navikey\/Metabolites\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">LIASmetabolites<\/a><\/em> en la p\u00e1gina del Botanische Staatssammlung M\u00fcnchen (Alemania).<\/p>\n\n\n\n<p>Todos los datos y cromatogramas tambi\u00e9n est\u00e1n disponibles en el <a href=\"https:\/\/www.lichenportal.org\/portal\/glossary\/index.php\" data-type=\"link\" data-id=\"https:\/\/www.lichenportal.org\/portal\/glossary\/index.php\" target=\"_blank\" rel=\"noreferrer noopener\">Glosario del Consorcio<\/a> de Herbarios de L\u00edquenes.<\/p>\n\n\n\n<p><font color=\"red\">Actualmente solamente existe la versi\u00f3n de Mytabolites en el idioma ingl\u00e9s. <\/font><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\"><strong>Para instalar Mytabolites<\/strong><\/h3>\n\n\n\n<p>Para la instalaci\u00f3n del programa, hay que crear una carpeta en la unidad de su sistema y descomprimir el archivo Zip. Despu\u00e9s se puede ejecutar el programa dando doble-clic en Mytabolites.exe. Si utiliza habitualmente el programa, cree un acceso directo para ejecutar el archivo.<\/p>\n\n\n\n<p><strong>IMPORTANTE:<\/strong>Este archivo es un archivo Zip que incluye un archivo ejecutable (Mytabolites.exe). Por razones de seguridad, muchas instituciones no permiten descargar ni ejecutar este tipo de archivos ejecutables.<\/p>\n\n\n\n<p>Windows 10 y Windows 11 suelen mostrar un mensaje de advertencia de que no se recomienda descargar o ejecutar el programa. Puede ignorar estos mensajes de seguridad, los archivos proporcionados son perfectamente seguros (como lo confirmar\u00e1 cualquier esc\u00e1ner de virus): <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"458\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/10\/image-1-1024x458.png\" alt=\"\" class=\"wp-image-2501\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/10\/image-1-1024x458.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/10\/image-1-300x134.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/10\/image-1.png 1647w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Aun as\u00ed, es posible que necesite permiso de su instituci\u00f3n para instalar\/ejecutar el programa. Comun\u00edquese con nosotros en caso de que tenga alg\u00fan problema (consulte los comentarios a continuaci\u00f3n).<\/p>\n\n\n\n<p class=\"has-medium-font-size\" id=\"descargar\"><strong>Descargar<\/strong> <strong>Mytabolites &#8230;<\/strong><\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-d4ac1ebb-9ca6-4ee7-9016-c3204c3e0f27\" href=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2026\/05\/Mytabolites.1.2.2.0-1.zip\">Mytabolites.1.2.2.0<\/a><a href=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2026\/05\/Mytabolites.1.2.2.0-1.zip\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d4ac1ebb-9ca6-4ee7-9016-c3204c3e0f27\">Mytabolites<\/a><\/div>\n\n\n\n<p>Este archivo Zip incluye los siguientes archivos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mytabolites.exe<\/strong> (el archivo de programa ejecutable; ejecute el programa haciendo doble clic o cree un acceso directo del archivo)<\/li>\n\n\n\n<li><strong>Mytabolites.db<\/strong> [una base de datos, necesario para que el programa acceda a los datos de cromatograf\u00eda (se puede actualizar desde el Consorcio de Herbarios de L\u00edquenes a trav\u00e9s de \u2018Sustancias &gt; Actualizar datos de sustancias\u2019)]<\/li>\n\n\n\n<li><strong>sqlite3.dll<\/strong> (el controlador SQLite es necesario para que el programa puede acceder la base de datos)<\/li>\n\n\n\n<li><strong>Default.cfg<\/strong> (la configuraci\u00f3n de b\u00fasqueda predeterminada; no modifique este archivo)<\/li>\n\n\n\n<li><strong>CurrentSearch.cfg <\/strong>(la configuraci\u00f3n de b\u00fasqueda personalizada seg\u00fan los par\u00e1metros m\u00e1s recientemente especificados<\/li>\n\n\n\n<li>La primera vez que usted actualice los datos de l\u00edquenes y sustancias secundarias desde del Consorcio, tambi\u00e9n se guardar\u00e1 un archivo de texto llamado <strong>UpdateDates.txt <\/strong>en el directorio del programa; cualquier archivo guardado con el programa tambi\u00e9n se guardar\u00e1 en la misma carpeta.<\/li>\n<\/ul>\n\n\n\n<p>Cuando ejecute el programa por primera vez, Mytabolites comprobar\u00e1 si hay una versi\u00f3n m\u00e1s nueva disponible y, si est\u00e1 disponible, le solicitar\u00e1 que la instale. Tambi\u00e9n puede buscar actualizaciones manualmente (ver instrucciones de actualizaci\u00f3n) a trav\u00e9s de \u2018<em>Help &gt; Help &gt; Program update<\/em>\u2019.<\/p>\n\n\n\n<p><font color=\"blue\">IMPORTANTE: Con el lanzamiento de Symbiota 3.1, Mytabolites ahora utiliza la interfaz de programaci\u00f3n de aplicaciones (API) integrada de Symbiota para actualizar datos del servidor. Mytabolites 1.1.2.0 es m\u00e1s estable y las rutinas de actualizaci\u00f3n se ejecutan m\u00e1s r\u00e1pido. Tambi\u00e9n hay algunas correcciones de errores menores y mejoras de funcionalidad. La versi\u00f3n m\u00e1s reciente, 1.1.2.3, es una actualizaci\u00f3n menor que ahora tambi\u00e9n incluye una verificaci\u00f3n de respaldo, es decir, verifica si la actualizaci\u00f3n de la base de datos se complet\u00f3 exitosamente y, en caso contrario, restaura la versi\u00f3n anterior de la base de datos..<\/font> <\/p>\n\n\n\n<p>Mytabolites incluye una base de datos con <em><strong>datos de cromatograf\u00eda <\/strong><\/em>(del cat\u00e1logo de Elix, es decir, informaci\u00f3n detallada sobre valores de RF, clases de sustancias, compuestos biosint\u00e9ticamente relacionados, colores en la placa de TLC antes y despu\u00e9s de hornear la placa, reacciones de prueba puntuales, etc.) y <em><strong>datos de l\u00edquenes<\/strong><\/em> (es decir, qu\u00e9 l\u00edquenes contienen metabolitos secundarios particulares seg\u00fan el <a href=\"https:\/\/lichenportal.org\/\" data-type=\"link\" data-id=\"https:\/\/lichenportal.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Consorcio de Herbarios de L\u00edquenes<\/a>).<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Actualizar el Programa:<\/h3>\n\n\n\n<p class=\"has-small-font-size\"><font color=\"red\">IMPORTANTE: Si todav\u00eda est\u00e1 usando 1.0.5.1. \u00a1debe actualizar antes de ejecutar cualquier actualizaci\u00f3n de la base de datos!<\/font><br>En la versi\u00f3n 1.0.5.1. el programa devolver\u00e1 un error interrumpiendo la actualizaci\u00f3n. Luego terminar\u00e1 usando un conjunto de datos incompleto (recientemente se lanz\u00f3 la versi\u00f3n 1.1.2.0 para solucionar este problema. Con el cambio de la API, otra vez es necesario actualizar el programa. <strong>La versi\u00f3n m\u00e1s reciente, 1.2.2.0<\/strong>.<\/p>\n\n\n\n<p>Los datos de cromatograf\u00eda incluidos en Mytabolites se pueden actualizar desde del Consorcio a trav\u00e9s de \u2018<em>Substances &gt; Update Substance Data<\/em>\u2018 (tenga en cuenta que si cambi\u00f3 manualmente alguna entrada para sustancias particulares usando el bot\u00f3n editar, estos cambios se sobrescribir\u00e1n cuando actualice los datos con los datos del Consorcio).<\/p>\n\n\n\n<p>La informaci\u00f3n sobre qu\u00e9 l\u00edquenes contienen sustancias particulares, los <em>Datos de L\u00edquenes<\/em>, se puede actualizar desde del Consorcio a trav\u00e9s de \u2018<em>Lichens &gt; Update Lichen Data<\/em>\u2019.<\/p>\n\n\n\n<p>Cada vez que se inicia Mytabolites, el programa comprueba si los datos de cromatograf\u00eda est\u00e1n actualizados. De lo contrario, se le solicitar\u00e1 hacer la actualizaci\u00f3n. Si los datos de Liquen tienen m\u00e1s de 80 d\u00edas, se le pedir\u00e1 que considere actualizar esa informaci\u00f3n tambi\u00e9n:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-13-1024x461.png\" alt=\"\" class=\"wp-image-1829\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-13-1024x461.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-13-300x135.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-13.png 1398w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Para obtener informaci\u00f3n detallada sobre c\u00f3mo utilizar el programa, consulte el archivo de ayuda integrado en \u2018<em>Help &gt; Help<\/em>\u2019.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Descripci\u00f3n general de la funcionalidad principal:<br><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Ventana principal y algoritmos de coincidencia (configuraci\u00f3n de b\u00fasqueda)<\/h4>\n\n\n\n<p>La ventana principal del programa permite ingresar datos de las manchas de las placas de la TLC procesadas en diferentes solventes a trav\u00e9s de \u2018Add TLC Spot\u2019. Inmediatamente despu\u00e9s de ingresar estos datos, para cada mancha se presenta una lista de posibles coincidencias de metabolitos secundarios. Las manchas se numeran autom\u00e1ticamente como \u2018Spot 1\u2019, \u2018Spot 2\u2019, etc. Para modificar estos datos haga doble-clic en el nombre de la mancha. Una vez modificados los datos, la lista se actualiza autom\u00e1ticamente. La lista resultante es m\u00e1s y m\u00e1s corta cuanto m\u00e1s informaci\u00f3n se ingrese (diferentes valores de RF en diferentes solventes, reacciones de color antes y despu\u00e9s del horneado de la placa, pruebas de tinci\u00f3n en el talo, etc.):<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-2-1024x741.png\" alt=\"\" class=\"wp-image-1813\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-2-1024x741.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-2-300x217.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-2.png 1414w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Generalmente, los resultados dependen de los valores de RF de las manchas en la placa de TLC ingresados. La precisi\u00f3n de estas coincidencias se puede mejorar a\u00fan m\u00e1s al incluir en los an\u00e1lisis los colores \u00ab<em>Before Charring<\/em>\u00bb y \u00ab<em>After Charring<\/em>\u00bb, tanto en luz visible como en luz ultravioleta. Si las placas fueron tratadas con soluci\u00f3n de Archer, ese color tambi\u00e9n se puede utilizar para obtener resultados m\u00e1s precisos. La lista resultante de las posibles coincidencias se puede reducir a\u00fan m\u00e1s ingresando las reacciones de las pruebas de tinci\u00f3n del talo de los l\u00edquenes y sus reacciones en luz UV.<\/p>\n\n\n\n<p>Dado que la percepci\u00f3n del color (tanto para las manchas de la placa de TLC como para las pruebas de tinci\u00f3n\/reacciones UV del talo) puede ser subjetiva, es posible desactivar los resultados coincidentes con los colores ingresados para ambos.<\/p>\n\n\n\n<p>Cuando se habilita \u2018coincidencia de colores\u2019, es posible usar dos algoritmos para el an\u00e1lisis (los criterios se pueden cambiar a trav\u00e9s de \u2018Search Configuration\u2019):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>RF Error<\/strong> es el algoritmo de coincidencia cl\u00e1sico empleado originalmente por <em>Wintabolites<\/em>. Este algoritmo simplemente compara el color de las manchas de la placa de TLC con posibles coincidencias incluidas en la base de datos. Dado que la percepci\u00f3n del color es subjetivo, la matriz tolera una cierta cantidad de variaci\u00f3n. Por ejemplo, el color \u00ablilac\u00bb (\u00ablila\u00bb) tambi\u00e9n se interpreta como \u00abwhite\u00bb (\u00abblanco\u00bb), \u00abpurple\u00bb (\u00abmorado\u00bb), \u00abpink\u00bb (\u00abrosa\u00bb),\u00abbright blue\u00bb (\u00abazul brillante\u00bb) y \u00abdark blue\u00bb(\u00abazul obscuro\u00bb). Al configurar la b\u00fasqueda como \u2018<em>RF Error<\/em>\u2019 en el programa simplemente utilice ausencia\/presencia de colores con un factor de tolerancia. El valor de este factor es un n\u00famero entero, normalmente 1 o 2.<\/li>\n\n\n\n<li><strong>Correlation<\/strong> utilice un algoritmo de coincidencia m\u00e1s \u00abdifuso\u00bb. En \u2018<em>Search Configuration<\/em>\u2019, la cantidad de tolerancia con la que los colores pueden desviarse se puede modificar con doble-clic. El factor de correlaci\u00f3n determina cu\u00e1ntas coincidencias a\u00fan se toleran. N\u00fameros m\u00e1s altos permiten m\u00e1s coincidencias. Un factor de correlaci\u00f3n de 5 generalmente funciona bien. Aumentar este factor significar\u00e1 que se encontrar\u00e1n m\u00e1s coincidencias, pero se ordenar\u00e1n con las mejores coincidencias en la parte superior.<\/li>\n\n\n\n<li>En <em>\u2018SearchConfiguration<\/em>\u2019 tambi\u00e9n es posible configurar si las pruebas de tinci\u00f3n y las reacciones UV del talo deben ser consideradas al comparar los datos.<\/li>\n\n\n\n<li>Con \u2018<em>Save As<\/em>\u2019 es posible guardar las configuraciones de b\u00fasqueda individuales. As\u00ed es posible re-utilizar diferentes configuraciones de b\u00fasqueda para el an\u00e1lisis.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"634\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-14-1024x634.png\" alt=\"\" class=\"wp-image-1831\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-14-1024x634.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-14-300x186.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-14.png 1188w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Guardar los resultados<\/h4>\n\n\n\n<p>Desde la ventana principal se puede guardar la lista real de las manchas de las placas de TLC como archivos para luego revisar\/actualizar estos datos nuevamente. As\u00ed, es posible por ejemplo ingresar los valores para un solvente, guardar el archivo y continuar posteriormente, a\u00f1adiendo informaci\u00f3n para otros solventes. Al ingresar m\u00e1s informaci\u00f3n a la lista de resultados, \u00e9sta se actualiza autom\u00e1ticamente, pero es necesario guardar estos cambios con \u2018<em>Save<\/em>\u2019.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Filtrar resultados de b\u00fasqueda<\/h4>\n\n\n\n<p>La lista de resultados se puede filtrar por g\u00e9nero (metabolitos secundarios reportadas seg\u00fan los datos disponibles en el Consorcio). Otro filtro permite reducir la lista por grupo de sustancias secundarias m\u00e1s probables. Adem\u00e1s es posible combinar los dos filtros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-15-1024x652.png\" alt=\"\" class=\"wp-image-1835\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-15-1024x652.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-15-300x191.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-15.png 1393w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Revisar la lista<\/h4>\n\n\n\n<p>Se pueden seleccionar sustancias individuales desde de la lista. Al hacer \u2018clic\u2019 con el bot\u00f3n derecho permite explorar los datos cromatogr\u00e1ficos detalladas a trav\u00e9s de \u2018<em>View Substance<\/em>\u2019. Tambi\u00e9n es posible ver una lista de las especies de l\u00edquenes con este metabolito secundario (\u2018<em>View Lichens<\/em>\u2019; la cantidad de especies se muestra al pasar el cursor sobre el nombre de la sustancia). Con \u2018<em>Sort by Match<\/em>\u2019 es posible ordenar la lista por coincidencia. Finalmente, el men\u00fa permite borrar todos los valores ingresados con \u2018<em>Clear All Entries<\/em>\u2019:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"438\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-6.png\" alt=\"\" class=\"wp-image-1817\" style=\"width:649px;height:auto\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-6.png 645w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-6-300x204.png 300w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/figure>\n\n\n\n<p>A trav\u00e9s de \u2018Substances &gt; View\/Edit Substances\u2019 se puede acceder y comparar informaci\u00f3n detallada sobre los metabolitos secundarios (es posible revisar esta base de datos sin ingresar TLC Spots en la ventana principal). Al dar \u2018clic\u2019 en el bot\u00f3n derecho, se permite comparar los datos de metabolitos biosint\u00e9ticamente relacionados:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-9-1024x544.png\" alt=\"\" class=\"wp-image-1822\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-9-1024x544.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-9-300x159.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-9.png 1701w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Si existe un cromatograma para una sustancia en particular, se puede usar el bot\u00f3n \u2018view\u2019 para mostrarlo (solo funciona cuando el programa tiene acceso a Internet):<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"617\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-8-1024x617.png\" alt=\"\" class=\"wp-image-1820\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-8-1024x617.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-8-300x181.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-8.png 1468w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Explorar los datos de metabolitos secundarios:<\/h3>\n\n\n\n<p>En el Cat\u00e1logo de Elix se incluye, para cada sustancia, una lista de Especies de Referencia (&#8216;<em>TLC-Reference Species<\/em>&#8216;) para las cuales se ha reportado dicha sustancia. Adem\u00e1s, el programa proporciona una lista de especies de las cuales se ha reportado esta sustancia de acuerdo al Consorcio. Al hacer doble-clic, se accede a la informaci\u00f3n disponible para dicha especie (las im\u00e1genes solo se muestran si existe una conexi\u00f3n a Internet y si hay im\u00e1genes disponibles; el bot\u00f3n \u2018<em>Lichen Consortium<\/em>\u2019 abre el perfil del tax\u00f3n en el navegador de la Internet):<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-10-1024x787.png\" alt=\"\" class=\"wp-image-1823\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-10-1024x787.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-10-300x230.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-10.png 1156w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Los datos de las sustancias no se pueden editar a menos que el modo \u00abread-only\u00bb est\u00e9 desactivado (<em>atenci\u00f3n<\/em>: al actualizar los datos del Consorcio, se sobrescribir\u00e1n todos los cambios manuales; para tener en cuenta la variaci\u00f3n en los valores de RF dependiendo de diferentes configuraciones experimentales, se recomienda ajustar los datos a trav\u00e9s de \u2018<em>Cune<\/em>\u2019, ver abajo).<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Explorar los datos de l\u00edquenes:<\/h3>\n\n\n\n<p>Es posible revisar la base de datos de l\u00edquenes de los cuales se han reportado metabolitos secundarios seg\u00fan el Consorcio. Se puede acceder a esta lista a trav\u00e9s de \u2018<em>Lichens\u2013 View lichens<\/em>\u2019, con un doble-clic en un nombre en esta lista o utilizando el \u2018<em>Search<\/em>\u2019 para reducir el tama\u00f1o de la lista. Desde de la lista de diferentes metabolitos reportados por la especie, es posible revisar los datos de cromatograf\u00eda dando un doble-clic.<\/p>\n\n\n\n<p>Images of the species are only displayed, if a connection to the internet exists and if an image of that species is available. If available, up to five images can be compared. The button &#8216;Lichen Consortium&#8217; opens the taxon profile page in the default browser):<\/p>\n\n\n\n<p>Las im\u00e1genes de la especie solo se muestran si existe una conexi\u00f3n a Internet y si alguna imagen de esa especie est\u00e1 disponible. Si est\u00e1 disponible en el Consorcio, se pueden comparar hasta cinco im\u00e1genes. El bot\u00f3n \u2018<em>Lichen Consortium<\/em>\u2019 abre el perfil del tax\u00f3n en el navegador de Internet):<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"879\" height=\"767\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-11.png\" alt=\"\" class=\"wp-image-1824\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-11.png 879w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-11-300x262.png 300w\" sizes=\"auto, (max-width: 879px) 100vw, 879px\" \/><\/figure>\n\n\n\n<p>Usando el bot\u00f3n \u2018<em>Copy<\/em>\u2019, se puede copiar la lista de metabolitos secundarios reportados para una especie (los nombres de las sustancias est\u00e1n separados por comas). El bot\u00f3n \u2018<em>Save<\/em>\u2019 crear\u00e1 un archivo de texto de esa lista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Calcular los valores de RF:<\/h3>\n\n\n\n<p>Desde de la ventana principal, el men\u00fa \u2018<em>Calculate<\/em>\u2019 abre una calculadora de RF para ingresar la distancia del centro de una mancha de la placa de TLC hasta la l\u00ednea de inicio al frente del solvente. Esta calculadora tambi\u00e9n est\u00e1 disponible haciendo doble-clic en el campo de los solventes enumerados en la ventana de ingreso de datos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mejorar la precisi\u00f3n y \u00ab<em>cunear<\/em>\u00bb (= calibrar) los datos:<\/h3>\n\n\n\n<p>Dependiendo de la configuraci\u00f3n experimental, es posible que los datos cromatogr\u00e1ficos puedan variar. La percepci\u00f3n del color, la l\u00e1mpara UV utilizada, la cantidad de tiempo y la temperatura a la que han estado expuestas las placas durante el horneado provocan variaciones que afecten la interpretaci\u00f3n de los resultados. Modificar la \u2018<em>Search Configuration<\/em>\u2019 para comparar estos resultados con diferentes algoritmos (&#8216;<em>RFError<\/em>&#8216;, &#8216;<em>Correlation<\/em>&#8216;) ayuda con la interpretaci\u00f3n de esta variabilidad. Correr placas en diferentes solventes mejora la precisi\u00f3n de los resultados. Es \u00fatil consultar la base de datos de l\u00edquenes de los que se han reportado metabolitos secundarios espec\u00edficos, pero estos datos obtenidos desde del Consorcio a\u00fan no est\u00e1n completos.<\/p>\n\n\n\n<p>Incluso teniendo en cuenta todos estos aspectos, interpretar los resultados puede seguir siendo dif\u00edcil, especialmente si la variaci\u00f3n experimental causa variaci\u00f3n significativa en los valores de RF. Los valores en el cat\u00e1logo de Elix se basan en una TLC estandarizada, utilizando placas de TLC regulares de 20 x 20 cm, en tanques de vidrio verticales. Los cromatogramas publicados por Schumm &amp; Elix (2015, 2016) corresponden a placas de TLC de 5 x 5 cm. En ASU utilizamos placas de 10 x 10 cm en tanques de TLC de alto rendimiento (HTLC).<\/p>\n\n\n\n<p>Al utilizar configuraciones experimentales tan diferentes, es particularmente importante incluir controles de metabolitos secundarios conocidos para calibrar los valores de RF. Generalmente se recomienda sustancias comunes como la atranorina o el \u00e1cido norstictico, pero en teor\u00eda es posible utilizar cualquier sustancia conocida. Wintabolites introdujo el concepto de &#8220;cuning&#8221; de los datos (el t\u00e9rmino refiere a Bruce McCune de la Oregon State University, quien fue el primero en sugerir este tipo de calibraci\u00f3n de valores de RF).<\/p>\n\n\n\n<p>Al utilizar configuraciones experimentales tan diferentes, es muy importante incluir controles de metabolitos secundarios conocidos para calibrar los valores de RF. Generalmente se recomienda usar sustancias comunes como la atranorina o el \u00e1cido norest\u00edctico, pero en teor\u00eda es posible utilizar cualquier sustancia conocida. <em>Wintabolites <\/em>introdujo el concepto de \u00abcuning\u00bb de los datos (el t\u00e9rmino hace referencia a Bruce McCune de Oregon State University, quien fue el primero en sugerir este tipo de calibraci\u00f3n de valores de RF).<\/p>\n\n\n\n<p>A trav\u00e9s de \u2018Cune\u2019 se puede a\u00f1adir una lista de sustancias conocidas (usando el bot\u00f3n \u2018+\u2019). Los valores publicados que figuran en el cat\u00e1logo de Elix se pueden modificar y reemplazarlos con los valores medidos\/observados en los diferentes solventes. Con \u2018Apply Cune\u2019 en la ventana principal, la lista de resultados se actualizar\u00e1 teniendo en cuenta los valores de RF que se desv\u00edan:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-12-1024x614.png\" alt=\"\" class=\"wp-image-1826\" srcset=\"https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-12-1024x614.png 1024w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-12-300x180.png 300w, https:\/\/help.lichenportal.org\/wp-content\/uploads\/2024\/07\/image-12.png 1377w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Citaci\u00f3n:<\/h2>\n\n\n\n<p><strong>Para publicaciones, sugerimos citar este programa\/sitio web de la siguiente manera:<\/strong><\/p>\n\n\n\n<p><strong>Lafferty, D., Bungartz, F., Elix, J.A. &amp; Schumm, F.<\/strong> (2024) Mytabolites \u2013 a program developed at Arizona State University for the interpretation thin-layer chromatography plates, for the analysis of secondary metabolites from lichens, based on an original concept published by E. Mietzsch, H.T. Lumbsch &amp; J.A. Elix. <em>Help &amp; Resources for the Consortium of Lichen Herbaria<\/em>, available at <a href=\"https:\/\/help.lichenportal.org\/index.php\/en\/analysis-of-secondary-metabolites\/\">https:\/\/help.lichenportal.org\/index.php\/en\/resources\/metabolites\/<\/a><\/p>\n\n\n\n<p><strong>Es posible que tambi\u00e9n desee citar los recursos principales<\/strong> (the <em>Chomatography Catalogue<\/em> by J.A. Elix and the <em>Chromatogram Atlas<\/em> by F. Schumm &amp; J.A.Elix)<strong> como sigue:<\/strong><\/p>\n\n\n\n<p><strong>Elix, J.A. <\/strong>(2022) <em>Catalogue of Standardized Chromatographic Data and Biosynthetic Relationships for Lichen Substances<\/em>. Sixth Edition. Published by the author, Canberra.<\/p>\n\n\n\n<p><strong>Schumm, F. &amp; Elix, J.A.<\/strong> (2015) <em>Atlas of Images of Thin Layer Chromatograms of Lichen Substances<\/em>. Books on Demand, Norderstedt.<\/p>\n\n\n\n<p><strong>Schumm, F. &amp; Elix, J.A.<\/strong> (2016) <em>Atlas of Images of Thin Layer Chromatograms of Lichen Substances<\/em>. Supplement. Books on Demand, Norderstedt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Comentarios:<\/h2>\n\n\n\n<p><strong>Agradecemos informes de errores y sugerencias: <\/strong><a href=\"mailto:LichenConsortium@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">LichenConsortium@gmail.com<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Agradecimientos:<\/h2>\n\n\n\n<p><strong>Traducci\u00f3n de la pagina:<\/strong> Dra. Mar\u00eda de los \u00c1ngeles (&#8216;Marusa&#8217;) Herrera-Campos, Dra. Rosa Emilia (&#8216;Rosy&#8217;) P\u00e9rez-P\u00e9rez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MYTABOLITES \u2013 un programa de Daryl Lafferty, Arizona State University \u2013 (Idea original: E. Mietzsch, H.T. Lumbsch &amp; J.A. Elix) [traducci\u00f3n de la pagina: Mar\u00eda de los \u00c1ngeles (Marusa) Herrera-Campos y Rosa Emilia P\u00e9rez-P\u00e9rez] IMPORTANTE !!! Actualice a la versi\u00f3n m\u00e1s reciente (1.2.2.0). Cuando intenta actualizar la base de datos con una versi\u00f3n anterior, parece <a href=\"https:\/\/help.lichenportal.org\/index.php\/es\/analisis-de-metabolitos-secundarios\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Software para la An\u00e1lisis de Metabolitos Secundarios<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1837","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/pages\/1837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":61,"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/pages\/1837\/revisions"}],"predecessor-version":[{"id":3627,"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/pages\/1837\/revisions\/3627"}],"wp:attachment":[{"href":"https:\/\/help.lichenportal.org\/index.php\/wp-json\/wp\/v2\/media?parent=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}